{"id":25717,"date":"2022-07-26T11:36:01","date_gmt":"2022-07-26T09:36:01","guid":{"rendered":"https:\/\/sigletos.gr\/?post_type=product&#038;p=25717"},"modified":"2026-06-18T10:29:36","modified_gmt":"2026-06-18T07:29:36","slug":"%ce%b3%cf%89%ce%bd%ce%b9%ce%b1-%ce%b5%ce%be%cf%89%cf%84%ce%b5%cf%83%cf%89%cf%84-%ce%bc%cf%80%ce%b1%ce%b6%ce%b1%cf%83-100%ce%bc%ce%bc-%ce%bc%ce%b5%cf%84%ce%b1%ce%b2%ce%bb%ce%b7%cf%84%ce%b7%cf%83-%ce%b3","status":"publish","type":"product","link":"https:\/\/sigletos.gr\/de\/produkt\/%ce%b3%cf%89%ce%bd%ce%b9%ce%b1-%ce%b5%ce%be%cf%89%cf%84%ce%b5%cf%83%cf%89%cf%84-%ce%bc%cf%80%ce%b1%ce%b6%ce%b1%cf%83-100%ce%bc%ce%bc-%ce%bc%ce%b5%cf%84%ce%b1%ce%b2%ce%bb%ce%b7%cf%84%ce%b7%cf%83-%ce%b3\/","title":{"rendered":"100MM BASIS AUSSENWINKEL VARIABLER WINKEL"},"content":{"rendered":"<p>100MM BASIS AUSSENWINKEL VARIABLER WINKEL<\/p>","protected":false},"excerpt":{"rendered":"<p>100MM BASIS AUSSENWINKEL VARIABLER WINKEL<\/p>","protected":false},"featured_media":25718,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[875,886],"product_tag":[1120,1136,1137],"class_list":{"0":"post-25717","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-875","7":"product_cat-886","8":"product_tag-1120","9":"product_tag-1136","10":"product_tag-1137","12":"first","13":"instock","14":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/sigletos.gr\/de\/wp-json\/wp\/v2\/product\/25717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sigletos.gr\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sigletos.gr\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/sigletos.gr\/de\/wp-json\/wp\/v2\/comments?post=25717"}],"version-history":[{"count":0,"href":"https:\/\/sigletos.gr\/de\/wp-json\/wp\/v2\/product\/25717\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sigletos.gr\/de\/wp-json\/wp\/v2\/media\/25718"}],"wp:attachment":[{"href":"https:\/\/sigletos.gr\/de\/wp-json\/wp\/v2\/media?parent=25717"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sigletos.gr\/de\/wp-json\/wp\/v2\/product_brand?post=25717"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sigletos.gr\/de\/wp-json\/wp\/v2\/product_cat?post=25717"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sigletos.gr\/de\/wp-json\/wp\/v2\/product_tag?post=25717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}