{"id":27913,"date":"2022-07-26T12:19:00","date_gmt":"2022-07-26T10:19:00","guid":{"rendered":"https:\/\/sigletos.gr\/?post_type=product&#038;p=27913"},"modified":"2022-08-01T08:12:53","modified_gmt":"2022-08-01T06:12:53","slug":"%ce%bf%ce%b4%ce%b7%ce%b3%cf%8c%cf%82-%ce%ac%ce%bd%cf%89","status":"publish","type":"product","link":"https:\/\/sigletos.gr\/it\/prodotto\/%ce%bf%ce%b4%ce%b7%ce%b3%cf%8c%cf%82-%ce%ac%ce%bd%cf%89\/","title":{"rendered":"Guida superiore"},"content":{"rendered":"<p>Guida superiore<\/p>","protected":false},"excerpt":{"rendered":"<p>Guida superiore<\/p>","protected":false},"featured_media":27914,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1350,902,900],"product_tag":[1133,1132,1157],"class_list":{"0":"post-27913","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-1350","7":"product_cat-902","8":"product_cat-900","9":"product_tag-1133","10":"product_tag-1132","11":"product_tag-1157","13":"first","14":"instock","15":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/sigletos.gr\/it\/wp-json\/wp\/v2\/product\/27913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sigletos.gr\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sigletos.gr\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/sigletos.gr\/it\/wp-json\/wp\/v2\/comments?post=27913"}],"version-history":[{"count":0,"href":"https:\/\/sigletos.gr\/it\/wp-json\/wp\/v2\/product\/27913\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sigletos.gr\/it\/wp-json\/wp\/v2\/media\/27914"}],"wp:attachment":[{"href":"https:\/\/sigletos.gr\/it\/wp-json\/wp\/v2\/media?parent=27913"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sigletos.gr\/it\/wp-json\/wp\/v2\/product_brand?post=27913"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sigletos.gr\/it\/wp-json\/wp\/v2\/product_cat?post=27913"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sigletos.gr\/it\/wp-json\/wp\/v2\/product_tag?post=27913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}