{"id":31080,"date":"2022-08-31T09:49:40","date_gmt":"2022-08-31T07:49:40","guid":{"rendered":"https:\/\/sigletos.gr\/?post_type=product&#038;p=31080"},"modified":"2022-08-31T09:49:40","modified_gmt":"2022-08-31T07:49:40","slug":"%ce%b3%cf%81%ce%b1%ce%bc%ce%bc%ce%b1%cf%84%ce%bf%ce%ba%ce%b9%ce%b2%cf%8e%cf%84%ce%b9%ce%bf-%ce%bb%ce%b9%ce%bc%ce%bf%ce%b6-%cf%83%ce%ba%ce%bf%cf%85%cf%81%ce%b9%ce%b1","status":"publish","type":"product","link":"https:\/\/sigletos.gr\/it\/prodotto\/%ce%b3%cf%81%ce%b1%ce%bc%ce%bc%ce%b1%cf%84%ce%bf%ce%ba%ce%b9%ce%b2%cf%8e%cf%84%ce%b9%ce%bf-%ce%bb%ce%b9%ce%bc%ce%bf%ce%b6-%cf%83%ce%ba%ce%bf%cf%85%cf%81%ce%b9%ce%b1\/","title":{"rendered":"LIMOUSINE (RUGGINE) Cassetta postale"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Una cassetta postale pratica per tutti i gusti<br \/>\ncon comodit\u00e0 e stile.<\/p>","protected":false},"featured_media":31082,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[883,875],"product_tag":[],"class_list":{"0":"post-31080","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-883","7":"product_cat-875","8":"pa_brand-viometal","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/sigletos.gr\/it\/wp-json\/wp\/v2\/product\/31080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sigletos.gr\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sigletos.gr\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/sigletos.gr\/it\/wp-json\/wp\/v2\/comments?post=31080"}],"version-history":[{"count":0,"href":"https:\/\/sigletos.gr\/it\/wp-json\/wp\/v2\/product\/31080\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sigletos.gr\/it\/wp-json\/wp\/v2\/media\/31082"}],"wp:attachment":[{"href":"https:\/\/sigletos.gr\/it\/wp-json\/wp\/v2\/media?parent=31080"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sigletos.gr\/it\/wp-json\/wp\/v2\/product_brand?post=31080"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sigletos.gr\/it\/wp-json\/wp\/v2\/product_cat?post=31080"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sigletos.gr\/it\/wp-json\/wp\/v2\/product_tag?post=31080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}